{"id":3577,"date":"2017-07-26T11:02:30","date_gmt":"2017-07-26T11:02:30","guid":{"rendered":"http:\/\/www.mataroempresa.cat\/?p=3577"},"modified":"2017-07-26T11:57:59","modified_gmt":"2017-07-26T11:57:59","slug":"cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext","status":"publish","type":"post","link":"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/","title":{"rendered":"Cerca de un centenar de personas encuentran trabajo mediante el programa InserText"},"content":{"rendered":"<p style=\"text-align: justify;\">El Ayuntamiento de Matar\u00f3 inici\u00f3 el proyecto <strong>InserText<\/strong>\u00a0en el a\u00f1o 2015 como proyecto piloto para contribuir a la recuperaci\u00f3n de uno de los principales sectores industriales de la comarca del Maresme, el sector del textil y la confecci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En las dos ediciones de <strong>InserText,\u00a0<\/strong>94 personas han encontrado trabajo gracias a este programa y la bolsa de trabajo del Servicio de Ocupaci\u00f3n de Matar\u00f3 (SOM) ha gestionado 188 ofertas de trabajo en el sector textil. En esta segunda edici\u00f3n 28 empresas han solicitado acogerse a la subvenci\u00f3n por contrataci\u00f3n que ofrece InserText. el ayuntamiento Destina 54.000\u20ac del presupuesto total del proyecto a esta acci\u00f3n. El a\u00f1o pasado se otorgaron 22.250\u20ac en concepto de subvenciones a las empresas.<\/p>\n<p style=\"text-align: justify;\">Para <a href=\"http:\/\/www.mataro.cat\/web\/portal\/contingut\/noticia\/2017\/07\/13574_cloenda_insertext.html\" target=\"_blank\">m\u00e1s informaci\u00f3n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Matar\u00f3 inici\u00f3 el proyecto InserText\u00a0en el a\u00f1o 2015 como proyecto piloto para contribuir a la recuperaci\u00f3n de uno de los principales sectores industriales de la comarca del [&hellip;]<span class=\"entry-read-more\"><a href=\"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/\" class=\"cs-btn cs-btn-flat cs-btn-rounded cs-btn-xxs cs-btn-flat-accent\">Leer m\u00e1s<\/a><\/span><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cerca de un centenar de personas encuentran trabajo mediante el programa InserText - Matar\u00f3 Empresa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cerca de un centenar de personas encuentran trabajo mediante el programa InserText - Matar\u00f3 Empresa\" \/>\n<meta property=\"og:description\" content=\"El Ayuntamiento de Matar\u00f3 inici\u00f3 el proyecto InserText\u00a0en el a\u00f1o 2015 como proyecto piloto para contribuir a la recuperaci\u00f3n de uno de los principales sectores industriales de la comarca del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/\" \/>\n<meta property=\"og:site_name\" content=\"Matar\u00f3 Empresa\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-26T11:02:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-07-26T11:57:59+00:00\" \/>\n<meta name=\"author\" content=\"Carme Navas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carme Navas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/\",\"url\":\"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/\",\"name\":\"Cerca de un centenar de personas encuentran trabajo mediante el programa InserText - Matar\u00f3 Empresa\",\"isPartOf\":{\"@id\":\"https:\/\/www.mataroempresa.cat\/es\/#website\"},\"datePublished\":\"2017-07-26T11:02:30+00:00\",\"dateModified\":\"2017-07-26T11:57:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.mataroempresa.cat\/es\/#\/schema\/person\/d3fb1bc92015affcf7834a96f57e0170\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.mataroempresa.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cerca de un centenar de personas encuentran trabajo mediante el programa InserText\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mataroempresa.cat\/es\/#website\",\"url\":\"https:\/\/www.mataroempresa.cat\/es\/\",\"name\":\"Matar\u00f3 Empresa\",\"description\":\"Matar\u00f3 Empresa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mataroempresa.cat\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mataroempresa.cat\/es\/#\/schema\/person\/d3fb1bc92015affcf7834a96f57e0170\",\"name\":\"Carme Navas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.mataroempresa.cat\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/61679110e418750597df6f6187929ebe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/61679110e418750597df6f6187929ebe?s=96&d=mm&r=g\",\"caption\":\"Carme Navas\"},\"url\":\"https:\/\/www.mataroempresa.cat\/es\/author\/cnavas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cerca de un centenar de personas encuentran trabajo mediante el programa InserText - Matar\u00f3 Empresa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/","og_locale":"es_ES","og_type":"article","og_title":"Cerca de un centenar de personas encuentran trabajo mediante el programa InserText - Matar\u00f3 Empresa","og_description":"El Ayuntamiento de Matar\u00f3 inici\u00f3 el proyecto InserText\u00a0en el a\u00f1o 2015 como proyecto piloto para contribuir a la recuperaci\u00f3n de uno de los principales sectores industriales de la comarca del [&hellip;]","og_url":"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/","og_site_name":"Matar\u00f3 Empresa","article_published_time":"2017-07-26T11:02:30+00:00","article_modified_time":"2017-07-26T11:57:59+00:00","author":"Carme Navas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carme Navas","Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/","url":"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/","name":"Cerca de un centenar de personas encuentran trabajo mediante el programa InserText - Matar\u00f3 Empresa","isPartOf":{"@id":"https:\/\/www.mataroempresa.cat\/es\/#website"},"datePublished":"2017-07-26T11:02:30+00:00","dateModified":"2017-07-26T11:57:59+00:00","author":{"@id":"https:\/\/www.mataroempresa.cat\/es\/#\/schema\/person\/d3fb1bc92015affcf7834a96f57e0170"},"breadcrumb":{"@id":"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mataroempresa.cat\/es\/cerca-de-un-centenar-de-personas-encuentran-trabajo-mediante-el-programa-insertext\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.mataroempresa.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Cerca de un centenar de personas encuentran trabajo mediante el programa InserText"}]},{"@type":"WebSite","@id":"https:\/\/www.mataroempresa.cat\/es\/#website","url":"https:\/\/www.mataroempresa.cat\/es\/","name":"Matar\u00f3 Empresa","description":"Matar\u00f3 Empresa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mataroempresa.cat\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.mataroempresa.cat\/es\/#\/schema\/person\/d3fb1bc92015affcf7834a96f57e0170","name":"Carme Navas","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.mataroempresa.cat\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/61679110e418750597df6f6187929ebe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/61679110e418750597df6f6187929ebe?s=96&d=mm&r=g","caption":"Carme Navas"},"url":"https:\/\/www.mataroempresa.cat\/es\/author\/cnavas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mataroempresa.cat\/es\/wp-json\/wp\/v2\/posts\/3577"}],"collection":[{"href":"https:\/\/www.mataroempresa.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mataroempresa.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mataroempresa.cat\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mataroempresa.cat\/es\/wp-json\/wp\/v2\/comments?post=3577"}],"version-history":[{"count":3,"href":"https:\/\/www.mataroempresa.cat\/es\/wp-json\/wp\/v2\/posts\/3577\/revisions"}],"predecessor-version":[{"id":3589,"href":"https:\/\/www.mataroempresa.cat\/es\/wp-json\/wp\/v2\/posts\/3577\/revisions\/3589"}],"wp:attachment":[{"href":"https:\/\/www.mataroempresa.cat\/es\/wp-json\/wp\/v2\/media?parent=3577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mataroempresa.cat\/es\/wp-json\/wp\/v2\/categories?post=3577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mataroempresa.cat\/es\/wp-json\/wp\/v2\/tags?post=3577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}